{"id":39,"date":"2022-05-13T13:07:57","date_gmt":"2022-05-13T13:07:57","guid":{"rendered":"https:\/\/littleteddiesnursery.com\/?page_id=39"},"modified":"2026-06-25T22:55:49","modified_gmt":"2026-06-25T22:55:49","slug":"little-teddies-prospectus","status":"publish","type":"page","link":"https:\/\/littleteddiesnursery.com\/index.php\/little-teddies-prospectus\/","title":{"rendered":"Parent Information"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"39\" class=\"elementor elementor-39\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2871f0d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2871f0d\" data-element_type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0432ae3\" data-id=\"0432ae3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8760cb5 elementor-widget elementor-widget-image\" data-id=\"8760cb5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 29-01-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/littleteddiesnursery.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"4500\" height=\"4500\" src=\"https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1.png\" class=\"attachment-full size-full wp-image-299\" alt=\"\" srcset=\"https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1.png 4500w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-300x300.png 300w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-1024x1024.png 1024w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-150x150.png 150w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-768x768.png 768w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-1536x1536.png 1536w, https:\/\/littleteddiesnursery.com\/wp-content\/uploads\/2022\/05\/Artboard-1-2048x2048.png 2048w\" sizes=\"(max-width: 4500px) 100vw, 4500px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8d323ae\" data-id=\"8d323ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2549e1a elementor-nav-menu__align-right elementor-nav-menu--stretch elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"2549e1a\" data-element_type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/littleteddiesnursery.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-nav-menu.min.css\">\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-2549e1a\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1071\"><a href=\"https:\/\/littleteddiesnursery.com\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-536\"><a href=\"http:\/\/littleteddiesgroup.co.uk\" class=\"elementor-item\">Visit our other Nurserys<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-75\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/about-us\/\" class=\"elementor-item\">About Us<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-606\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/our-policies\/\" class=\"elementor-sub-item\">Our Policies<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-990\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/our-rooms\/\" class=\"elementor-sub-item\">Our Rooms \u2013 New<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-545\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/meet-the-staff\/\" class=\"elementor-sub-item\">Meet the staff<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-115\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/gallery\/\" class=\"elementor-sub-item\">Gallery<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-114\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/little-teddies-prospectus\/\" class=\"elementor-item\">Parent Information<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-74\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/contact-us\/\" class=\"elementor-item\">Contact Us<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-856\"><a href=\"https:\/\/app.famly.co\/#\/inquiry?institutionId=1c99719c-61ea-43df-bb51-c0932eb0bc9f&#038;hmac=4f694c2d7af174b4042c31f74f3bff47c04a3911df4579849a21044a6724de0f&#038;locale=en_GB\" class=\"elementor-item elementor-item-anchor\">Feedback<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-2549e1a\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1071\"><a href=\"https:\/\/littleteddiesnursery.com\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-536\"><a href=\"http:\/\/littleteddiesgroup.co.uk\" class=\"elementor-item\" tabindex=\"-1\">Visit our other Nurserys<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-75\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/about-us\/\" class=\"elementor-item\" tabindex=\"-1\">About Us<\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-606\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/our-policies\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Our Policies<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-990\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/our-rooms\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Our Rooms \u2013 New<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-545\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/meet-the-staff\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Meet the staff<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-115\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/gallery\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Gallery<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-114\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/little-teddies-prospectus\/\" class=\"elementor-item\" tabindex=\"-1\">Parent Information<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-74\"><a href=\"https:\/\/littleteddiesnursery.com\/index.php\/contact-us\/\" class=\"elementor-item\" tabindex=\"-1\">Contact Us<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-856\"><a href=\"https:\/\/app.famly.co\/#\/inquiry?institutionId=1c99719c-61ea-43df-bb51-c0932eb0bc9f&#038;hmac=4f694c2d7af174b4042c31f74f3bff47c04a3911df4579849a21044a6724de0f&#038;locale=en_GB\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Feedback<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf42141 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf42141\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afb8b50\" data-id=\"afb8b50\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df0b69 elementor-widget elementor-widget-heading\" data-id=\"2df0b69\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.19.0 - 29-01-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Parent Information<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b1ceea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b1ceea\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b80de53\" data-id=\"b80de53\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8abb24 elementor-widget elementor-widget-html\" data-id=\"f8abb24\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"_df_book df-lite\" id=\"df_1118\"  _slug=\"parent-handbook-2026\" data-title=\"parent-handbook-2026\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" type=\"application\/javascript\">window.option_df_1118 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"source\":\"http:\\\/\\\/littleteddiesnursery.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Little-Teddies-Parent-Pack-2025-2-1.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-233bfd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"233bfd5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffec50a\" data-id=\"ffec50a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c455c43 elementor-widget elementor-widget-html\" data-id=\"c455c43\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"_df_book df-lite\" id=\"df_1111\"  _slug=\"price-list-2026\" data-title=\"price-list-2026\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" type=\"application\/javascript\">window.option_df_1111 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"source\":\"http:\\\/\\\/littleteddiesnursery.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Untitled-design-2.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Parent Information<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/pages\/39"}],"collection":[{"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":128,"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":1158,"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/pages\/39\/revisions\/1158"}],"wp:attachment":[{"href":"https:\/\/littleteddiesnursery.com\/index.php\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}